{"id":2201,"date":"2018-08-02T10:42:36","date_gmt":"2018-08-02T10:42:36","guid":{"rendered":"http:\/\/dev.davidorban.com\/?p=2201"},"modified":"2018-08-27T14:58:51","modified_gmt":"2018-08-27T14:58:51","slug":"la-tecnologia-genera-la-societa-del-futuro","status":"publish","type":"post","link":"https:\/\/davidorban.com\/it\/2018\/08\/la-tecnologia-genera-la-societa-del-futuro\/","title":{"rendered":"La tecnologia genera la societ\u00e0 del futuro"},"content":{"rendered":"<p>In un&#8217;intervista con Bruno Ruffilli per TuttoScienze di&nbsp;<a href=\"http:\/\/www.lastampa.it\/\">La Stampa<\/a>, abbiamo parlato di come il progresso tecnologico possa generare nuovi gradi di libert\u00e0.<\/p>\n<hr>\n<p><center><\/p>\n<h3>&#8220;La tecnologia, amica incompresa&#8221;<br \/>\nOrban: sta generando la societ\u00e0 del futuro<\/h3>\n<p><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><b><\/b><em>di Bruno Ruffilli<\/em><\/p>\n<p style=\"text-align: left;\">David Orban, 53 anni, ungherese, \u00e8 docente alla Singularity University, che assiste le aziende nel percorso di innovazione. Ha fondato Network Society Research, dove si studiano tecnologie decentralizzate e distribuite come la Blockchain. E, mentre tanti parlano del futuro, lui lo sperimenta sulla sua pelle, anzi sotto: si \u00e8 fatto impiantare un chip \u00abnfc\u00bb, che \u00e8 diventato biglietto da visita digitale, chiave di casa, password del conto corrente. Orban viaggia in tutto il mondo, ma passa molto tempo in Italia, dove le sue visioni del futuro sembrano oggi pi\u00f9 che mai lontane.<\/p>\n<p><\/center>Da alleata che era, ora la tecnologia diventa spesso un nemico da combattere. Come mai?<\/p>\n<p>\u00abSempre pi\u00f9 persone hanno difficolt\u00e0 a specchiarsi nella realt\u00e0 che cambia cos\u00ec velocemente e intuiscono di essere giunte ai limiti della propria adattabilit\u00e0. Si sentono allora inutili: a se stessi, alla societ\u00e0, alla comunit\u00e0\u00bb.<\/p>\n<p>La tecnologia pu\u00f2 aiutarci?<\/p>\n<p>\u00abLa sequenza tradizionale vede prima la politica, poi la societ\u00e0 e quindi la tecnologia, ma \u00e8 l\u2019opposto di quello che avviene: \u00e8 la tecnologia che ci permette di esprimere una certa societ\u00e0 e la nostra idea di futuro \u00e8 modellata spesso sulle promesse del progresso tecnologico. Perci\u00f2 dobbiamo chiederci in modo non dogmatico che tipo di societ\u00e0 pu\u00f2 esprimere la tecnologia attuale e quale sia forma di governo di cui deve dotarsi\u00bb.<\/p>\n<p>Grillo \u00e8 riuscito a dare l\u2019idea che tutti possano partecipare alla politica, o diffondere notizie, e cos\u00ec ora la fiducia nelle istituzioni e nei giornali \u00e8 crollata.<\/p>\n<p>\u00abQui c\u2019\u00e8 un falso sillogismo: dal momento che su un certo argomento gli scienziati non hanno la certezza assoluta, allora tutti gli scienziati sono inaffidabili. \u00c8 una logica sbagliata. E poi le tecnologie vanno gestite, le loro implicazioni comprese: quando abbiamo inventato il fuoco, all\u2019inizio ci siamo bruciati, ma poi abbiamo capito come usarlo. Cos\u00ec l\u2019esaltante capacit\u00e0 di diffondere un messaggio, che Internet offre a chiunque, \u00e8 oggetto di abuso da parte di abili manipolatori e noi dobbiamo imparare a riconoscere le fake news. Questa coscienza critica far\u00e0 bene anche ai giornali, separer\u00e0 quelli che riportano la verit\u00e0 dagli altri. Altrimenti continueremo ad andare avanti con le scie chimiche\u00bb.<\/p>\n<p>Ci salver\u00e0 la Blockchain?<\/p>\n<p>\u00abLo Stato-nazione per come lo conosciamo ha avuto un ruolo fondamentale nella storia, ma oggi la tecnologia consente agli individui nuove forme di libert\u00e0. Prendiamo il limite monetario: se esco dall\u2019Italia non posso portare con me pi\u00f9 di 10 mila euro, ma se ho investito in Bitcoin? La network society, la societ\u00e0 interconnessa, trascende la dimensione nazionale. Inevitabilmente gli Stati attuali si opporranno a questa evoluzione, ma la storia dice che \u00e8 inutile cercare di contrastare il futuro\u00bb.<\/p>\n<p>E intanto Facebook \u00e8 gi\u00e0 una potentissima organizzazione sovranazionale, con 2,2 miliardi di persone.<\/p>\n<p>\u00ab\u00c8 sovranazionale ma centralizzata. E la centralizzazione contiene relazioni perverse di vulnerabilit\u00e0 desiderabili: le ha svelate ad esempio Edward Snowden\u00bb.<\/p>\n<p>Ma pure dal caso Cambridge Analytica&#8230;<\/p>\n<p>\u00abDobbiamo ripensare l\u2019intera architettura di Internet in modo che sia decentralizzata e la Blockchain giocher\u00e0 un ruolo molto importante\u00bb.<\/p>\n<p>Non render\u00e0 l\u2019accesso alla tecnologia pi\u00f9 limitato?<\/p>\n<p>\u00abLa tecnologia avanzata, da elitaria diventa democratica. Cent\u2019anni fa era possibile avere un ruolo nella societ\u00e0 pur essendo analfabeti, oggi \u00e8 impensabile. Ma la tecnologia ci ha reso pi\u00f9 ricchi, cos\u00ec le societ\u00e0 moderne possono permettersi di dare a tutti la libert\u00e0 di vivere come vogliono, anche senza tecnologia. Una volta queste persone sarebbero state escluse, oggi anche loro godono del progresso\u00bb.<\/p>\n<p><a href=\"https:\/\/creativecommons.org\/licenses\/by-nc-nd\/3.0\/it\/deed.it\"><em>CC-BY-NC-ND La Stampa Alcuni diritti riservati<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un&#8217;intervista con Bruno Ruffilli per TuttoScienze di&nbsp;La Stampa, abbiamo parlato di come il progresso tecnologico possa generare nuovi gradi di libert\u00e0. &#8220;La tecnologia, amica incompresa&#8221; Orban: sta generando la societ\u00e0 del futuro di Bruno Ruffilli David Orban, 53 anni, ungherese, \u00e8 docente alla Singularity University, che assiste le aziende nel percorso di innovazione. Ha [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[728,1773,920],"tags":[2281,2611],"class_list":["post-2201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generale","category-intervista","category-tecnologia","tag-futuro-it","tag-persone-it"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/posts\/2201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/comments?post=2201"}],"version-history":[{"count":0,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/posts\/2201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/media\/2202"}],"wp:attachment":[{"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/media?parent=2201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/categories?post=2201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/davidorban.com\/it\/wp-json\/wp\/v2\/tags?post=2201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}